{"id":1016,"date":"2021-10-17T21:44:40","date_gmt":"2021-10-18T02:44:40","guid":{"rendered":"https:\/\/mostrafilmfestival.org\/xii\/?post_type=portfolio&#038;p=1016"},"modified":"2021-10-18T17:21:56","modified_gmt":"2021-10-18T22:21:56","slug":"the-lady-from-estacio","status":"publish","type":"portfolio","link":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/","title":{"rendered":"The Lady From Est\u00e1cio"},"content":{"rendered":"<div id='av_section_1'  class='avia-section av-vcz8nc-a43466a39691ef8e7ad492b009af6e2d main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll  container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-1016'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-t03wd4-b8c4f619e6f4ac4b4a3f9158c8b09b16\">\n.flex_column.av-t03wd4-b8c4f619e6f4ac4b4a3f9158c8b09b16{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-t03wd4-b8c4f619e6f4ac4b4a3f9158c8b09b16 av_one_third  avia-builder-el-1  el_before_av_two_third  avia-builder-el-first  first flex_column_div av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kuw20dba-284064acde15cc5ae5c7f22d3eac1f9a\">\n.avia-image-container.av-kuw20dba-284064acde15cc5ae5c7f22d3eac1f9a .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kuw20dba-284064acde15cc5ae5c7f22d3eac1f9a av-styling- avia-align-center  avia-builder-el-2  el_before_av_hr  avia-builder-el-first  '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-701x1030.jpg\" data-srcset=\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-701x1030.jpg 701w, https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-204x300.jpg 204w, https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-768x1128.jpg 768w, https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-480x705.jpg 480w, https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg 1000w\" data-sizes=\"(max-width: 701px) 100vw, 701px\" class='avia_image' ><img decoding=\"async\" width=\"701\" height=\"1030\" class='wp-image-1017 avia-img-lazy-loading-not-1017 avia_image' src=\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-701x1030.jpg\" alt='' title='adamadoestacio_cartaz_caixao_pt_peq'  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-701x1030.jpg 701w, https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-204x300.jpg 204w, https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-768x1128.jpg 768w, https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq-480x705.jpg 480w, https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg 1000w\" sizes=\"(max-width: 701px) 100vw, 701px\" \/><\/a><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-qzjdfs-a89a0f88b65bb5df99ccad7b6abafbdc\">\n#top .hr.hr-invisible.av-qzjdfs-a89a0f88b65bb5df99ccad7b6abafbdc{\nheight:15px;\n}\n<\/style>\n<div  class='hr av-qzjdfs-a89a0f88b65bb5df99ccad7b6abafbdc hr-invisible  avia-builder-el-3  el_after_av_image  avia-builder-el-last  '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-qfl4yg-d296fe734391cdf52253001086ac990c\">\n.flex_column.av-qfl4yg-d296fe734391cdf52253001086ac990c{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-qfl4yg-d296fe734391cdf52253001086ac990c av_two_third  avia-builder-el-4  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding '   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kuw1zkrd-5ae87389f54825dae5c41b0cf845cd53\">\n#top .av-special-heading.av-kuw1zkrd-5ae87389f54825dae5c41b0cf845cd53{\npadding-bottom:10px;\nfont-size:50px;\n}\n<\/style>\n<div  class='av-special-heading av-kuw1zkrd-5ae87389f54825dae5c41b0cf845cd53 av-special-heading-h1 blockquote modern-quote  avia-builder-el-5  el_before_av_textblock  avia-builder-el-first  av-inherit-size '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >THE LADY FROM EST\u00c1CIO<\/h1><div class='special-heading-border'><div class='special-heading-inner-border'><\/div><\/div><\/div><br \/>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><p><strong>Original Title:<\/strong> A Dama do Est\u00e1cio<br \/>\n<strong>Director:<\/strong> Eduardo Ades<br \/>\n<em>Fiction \/ 22min \/ 2012<\/em><br \/>\nPortuguese with English Subtitles<\/p>\n<p>Zulmira is an old mistress. One day she wakes up obsessed with the idea of dying. All she needs is a good coffin.<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-nog1aw-4bb77e8e98439049435a1a9a50523acc\">\n@keyframes av_sonarEffect_av-nog1aw-4bb77e8e98439049435a1a9a50523acc {\n  0% {opacity: 0.3;}\n 40% {opacity: 0.5; box-shadow: 0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #ffffff, 0 0 0 10px rgba(255,255,255,0.5);}\n100% {opacity: 0; box-shadow: 0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #ffffff, 0 0 0 10px rgba(255,255,255,0.5); -webkit-transform: scale(1.5); transform: scale(1.5);}\n}\n@-webkit-keyframes av_sonarEffect_av-nog1aw-4bb77e8e98439049435a1a9a50523acc {\n  0% {opacity: 0.3;}\n 40% {opacity: 0.5; box-shadow: 0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #ffffff, 0 0 0 10px rgba(255,255,255,0.5);}\n100% {opacity: 0; box-shadow: 0 0 0 2px rgba(255,255,255,0.1), 0 0 10px 10px #ffffff, 0 0 0 10px rgba(255,255,255,0.5); -webkit-transform: scale(1.5); transform: scale(1.5);}\n}\n#top .avia-icon-list-container.av-nog1aw-4bb77e8e98439049435a1a9a50523acc .iconlist_icon{\ncolor:#17178e;\n}\n#top .avia-icon-list-container.av-nog1aw-4bb77e8e98439049435a1a9a50523acc .iconlist_icon:hover:after{\nanimation:av_sonarEffect_av-nog1aw-4bb77e8e98439049435a1a9a50523acc 1s ease-in-out;\n-webkit-animation:av_sonarEffect_av-nog1aw-4bb77e8e98439049435a1a9a50523acc 1s ease-in-out;\n-moz-animation:av_sonarEffect_av-nog1aw-4bb77e8e98439049435a1a9a50523acc 1s ease-in-out;\n-o-animation:av_sonarEffect_av-nog1aw-4bb77e8e98439049435a1a9a50523acc 1s ease-in-out;\n}\n<\/style>\n<div  class='avia-icon-list-container av-nog1aw-4bb77e8e98439049435a1a9a50523acc  avia-builder-el-7  el_after_av_textblock  avia-builder-el-last  '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-nog1aw-4bb77e8e98439049435a1a9a50523acc avia-iconlist-animate avia-sonar-shadow'>\n<li><div class='iconlist_icon av-ly6iuw-0a1f963302903842c82bfc8e791a8f39 avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue826' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title   '  itemprop=\"headline\" >Watch Online<\/h4><\/header><div class='iconlist_content  '  itemprop=\"text\" ><p>Availability to be announced.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<\/ul><\/div><\/p><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-kad3pk-1c9c69f42c08cc0ceb79de87272d5d21 main_color avia-section-default avia-no-shadow  avia-builder-el-8  el_after_av_section  el_before_av_section  avia-bg-style-scroll  container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-1016'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column av-iu6vyw-843973287ad6ab52c77d2996ebd25e39 av_one_third  avia-builder-el-9  el_before_av_two_third  avia-builder-el-first  first flex_column_div '   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-h5jgko-ee023f61dc6a7fa0a68e8936787ab937\">\n#top .av-special-heading.av-h5jgko-ee023f61dc6a7fa0a68e8936787ab937{\npadding-bottom:25px;\nfont-size:40px;\n}\n<\/style>\n<div  class='av-special-heading av-h5jgko-ee023f61dc6a7fa0a68e8936787ab937 av-special-heading-h3 blockquote modern-quote modern-centered  avia-builder-el-10  avia-builder-el-no-sibling  av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Watch the teaser<\/h3><div class='special-heading-border'><div class='special-heading-inner-border'><\/div><\/div><\/div><\/div><div class='flex_column av-frt4ew-8b9171209a53c181e7d692710e79d585 av_two_third  avia-builder-el-11  el_after_av_one_third  el_before_av_one_full  flex_column_div '   ><div  class='avia-video avia-video-16-9   av-lazyload-immediate  av-lazyload-video-embed  '   itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/FDCzFUQ9lYY' ><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"A dama do Est\u00e1cio (The Lady from Estacio) - teaser\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/FDCzFUQ9lYY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1g4b2w-5fced2c836e62d1e047dd02bbdf5552b\">\n.flex_column.av-1g4b2w-5fced2c836e62d1e047dd02bbdf5552b{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-1g4b2w-5fced2c836e62d1e047dd02bbdf5552b av_one_full  avia-builder-el-13  el_after_av_two_third  avia-builder-el-last  first flex_column_div av-zero-column-padding column-top-margin'   ><div  class='av-social-sharing-box av-social-sharing-box-default   avia-builder-el-14  avia-builder-el-no-sibling  av-social-sharing-box-fullwidth '><div class=\"av-share-box\"><h5 class='av-share-link-description av-no-toc '>Share it!<\/h5><ul class=\"av-share-box-list noLightbox\"><li class='av-share-link av-social-link-facebook' ><a target=\"_blank\" aria-label=\"Share on Facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/&amp;t=The%20Lady%20From%20Est%C3%A1cio\" aria-hidden=\"false\" data-av_icon=\"\ue8f3\" data-av_iconfont=\"entypo-fontello\" title=\"\" data-avia-related-tooltip=\"Share on Facebook\" rel=\"noopener\"><span class='avia_hidden_link_text'>Share on Facebook<\/span><\/a><\/li><li class='av-share-link av-social-link-twitter' ><a target=\"_blank\" aria-label=\"Share on Twitter\" href=\"https:\/\/twitter.com\/share?text=The%20Lady%20From%20Est%C3%A1cio&amp;url=https:\/\/mostrafilmfestival.org\/xii\/?p=1016\" aria-hidden=\"false\" data-av_icon=\"\ue8f1\" data-av_iconfont=\"entypo-fontello\" title=\"\" data-avia-related-tooltip=\"Share on Twitter\" rel=\"noopener\"><span class='avia_hidden_link_text'>Share on Twitter<\/span><\/a><\/li><li class='av-share-link av-social-link-whatsapp' ><a target=\"_blank\" aria-label=\"Share on WhatsApp\" href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/\" aria-hidden=\"false\" data-av_icon=\"\uf232\" data-av_iconfont=\"entypo-fontello\" title=\"\" data-avia-related-tooltip=\"Share on WhatsApp\" rel=\"noopener\"><span class='avia_hidden_link_text'>Share on WhatsApp<\/span><\/a><\/li><li class='av-share-link av-social-link-linkedin' ><a target=\"_blank\" aria-label=\"Share on LinkedIn\" href=\"https:\/\/linkedin.com\/shareArticle?mini=true&amp;title=The%20Lady%20From%20Est%C3%A1cio&amp;url=https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/\" aria-hidden=\"false\" data-av_icon=\"\ue8fc\" data-av_iconfont=\"entypo-fontello\" title=\"\" data-avia-related-tooltip=\"Share on LinkedIn\" rel=\"noopener\"><span class='avia_hidden_link_text'>Share on LinkedIn<\/span><\/a><\/li><li class='av-share-link av-social-link-mail' ><a  aria-label=\"Share by Mail\" href='mailto:?subject=The%20Lady%20From%20Est%C3%A1cio&#038;body=https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/' aria-hidden='false' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Share by Mail'><span class='avia_hidden_link_text'>Share by Mail<\/span><\/a><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_3'  class='avia-section av-am2qjc-e5d6606ca1f95d2fa7d9c59b34c17ef1 main_color avia-section-default avia-no-border-styling  avia-builder-el-15  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll  container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-1016'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column av-9fogjs-953162339001aab4dee55f8256489fe0 av_three_fourth  avia-builder-el-16  el_before_av_one_fourth  avia-builder-el-first  first flex_column_div '   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7p2y08-733e9e7cb055c3b2dfccfd57fad456f3\">\n#top .av-special-heading.av-7p2y08-733e9e7cb055c3b2dfccfd57fad456f3{\npadding-bottom:10px;\nfont-size:35px;\n}\n<\/style>\n<div  class='av-special-heading av-7p2y08-733e9e7cb055c3b2dfccfd57fad456f3 av-special-heading-h3 blockquote modern-quote modern-centered  avia-builder-el-17  avia-builder-el-no-sibling  av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Films you may be interested in:<\/h3><div class='special-heading-border'><div class='special-heading-inner-border'><\/div><\/div><\/div><\/div><div class='flex_column av-64v72g-b881eb1c18f4e5e5a23fd9ffb460243f av_one_fourth  avia-builder-el-18  el_after_av_three_fourth  el_before_av_hr  flex_column_div '   ><div  class='avia-button-wrap avia-button-center  avia-builder-el-19  avia-builder-el-no-sibling ' ><a href='https:\/\/mostrafilmfestival.org\/xii\/films\/'  class='avia-button av-41zq14-2dd3ca6ea65782cb138f42daf4b71179 avia-icon_select-yes-left-icon avia-size-large avia-position-center av-icon-on-hover avia-color-theme-color ' ><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue817' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >SEE ALL FILMS<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-34ub2g-90cc794af0ecaf99cae6dd367e65a387\">\n#top .hr.hr-invisible.av-34ub2g-90cc794af0ecaf99cae6dd367e65a387{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-34ub2g-90cc794af0ecaf99cae6dd367e65a387 hr-invisible  avia-builder-el-20  el_after_av_one_fourth  el_before_av_masonry_entries  avia-builder-el-last  '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div id='av-masonry-1' class='av-masonry av-kuw1z63j-21561ae3d54d73d7b8310328cbdcee56 noHover av-fixed-size av-1px-gap av-hover-overlay-active av-masonry-animation-active av-masonry-col-6 av-caption-on-hover av-caption-style-overlay av-masonry-entries av-orientation-portrait-large    av-small-columns-overwrite av-small-columns-2 av-mini-columns-overwrite av-mini-columns-2'><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image '><\/div><a href=\"https:\/\/mostrafilmfestival.org\/xii\/films\/great-return\/\"  id='av-masonry-1-item-758' data-av-masonry-item='758' class='av-masonry-entry isotope-item post-758 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-short-documentary portfolio_entries-short-film  av-masonry-item-with-image' title=\"Volta Grande_poster\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/Volta-Grande_poster-397x705.png);\"  title=\"Volta Grande_poster\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Great Return<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/mostrafilmfestival.org\/xii\/films\/you-have-sad-eyes\/\"  id='av-masonry-1-item-775' data-av-masonry-item='775' class='av-masonry-entry isotope-item post-775 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-short-fiction portfolio_entries-short-film  av-masonry-item-with-image' title=\"cartaz_VTOT\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/cartaz_VTOT-470x705.jpeg);\"  title=\"cartaz_VTOT\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >You Have Sad Eyes<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/mostrafilmfestival.org\/xii\/films\/joao-o-maestro\/\"  id='av-masonry-1-item-592' data-av-masonry-item='592' class='av-masonry-entry isotope-item post-592 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-biography portfolio_entries-feature portfolio_entries-feature-fiction portfolio_entries-online  av-masonry-item-with-image' title=\"Cartaz &#8211; Joao o Maestro\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/Cartaz-Joao-o-Maestro-483x705.jpg);\"  title=\"Cartaz &#8211; Joao o Maestro\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Jo\u00e3o, O Maestro<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/mostrafilmfestival.org\/xii\/films\/flesh\/\"  id='av-masonry-1-item-749' data-av-masonry-item='749' class='av-masonry-entry isotope-item post-749 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-short-animation portfolio_entries-short-documentary portfolio_entries-short-film  av-masonry-item-with-image' title=\"Flesh-official-poster (1920&#215;1080)\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/Flesh-official-poster-1920x1080-1-499x705.jpg);\"  title=\"Flesh-official-poster (1920&#215;1080)\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Flesh<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-last-game\/\"  id='av-masonry-1-item-433' data-av-masonry-item='433' class='av-masonry-entry isotope-item post-433 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-comedy portfolio_entries-feature portfolio_entries-feature-fiction portfolio_entries-in-person portfolio_entries-online  av-masonry-item-with-image' title=\"O \u00daLTIMO JOGO_Official Poster\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/09\/O-ULTIMO-JOGO_Official-Poster-479x705.jpg);\"  title=\"O \u00daLTIMO JOGO_Official Poster\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >The Last Game<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/mostrafilmfestival.org\/xii\/films\/pacarrete\/\"  id='av-masonry-1-item-406' data-av-masonry-item='406' class='av-masonry-entry isotope-item post-406 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_entries-comedy portfolio_entries-drama portfolio_entries-feature portfolio_entries-feature-fiction portfolio_entries-in-person portfolio_entries-online  av-masonry-item-with-image' title=\"Pacarrete &#8211; Official Poster\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/09\/Pacarrete-Official-Poster-480x705.jpg);\"  title=\"Pacarrete &#8211; Official Poster\"  ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Pacarrete<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><\/div><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Zulmira is an old mistress. One day she wakes up obsessed with the idea of dying. All she needs is a good coffin.<\/p>\n","protected":false},"featured_media":1017,"comment_status":"open","ping_status":"closed","template":"","tags":[],"portfolio_entries":[23,9],"class_list":["post-1016","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-short-fiction","portfolio_entries-short-film"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Lady From Est\u00e1cio - MOSTRA XII: Brazilian Film Festival<\/title>\n<meta name=\"description\" content=\"Zulmira is an old mistress. One day she wakes up obsessed with the idea of dying. All she needs is a good coffin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Lady From Est\u00e1cio - MOSTRA XII: Brazilian Film Festival\" \/>\n<meta property=\"og:description\" content=\"Zulmira is an old mistress. One day she wakes up obsessed with the idea of dying. All she needs is a good coffin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/\" \/>\n<meta property=\"og:site_name\" content=\"MOSTRA XII: Brazilian Film Festival\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mostrafilmfestival\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T22:21:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@brazilianfilms\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/\",\"url\":\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/\",\"name\":\"The Lady From Est\u00e1cio - MOSTRA XII: Brazilian Film Festival\",\"isPartOf\":{\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg\",\"datePublished\":\"2021-10-18T02:44:40+00:00\",\"dateModified\":\"2021-10-18T22:21:56+00:00\",\"description\":\"Zulmira is an old mistress. One day she wakes up obsessed with the idea of dying. All she needs is a good coffin.\",\"breadcrumb\":{\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#primaryimage\",\"url\":\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg\",\"contentUrl\":\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg\",\"width\":1000,\"height\":1469},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mostrafilmfestival.org\/xii\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Lady From Est\u00e1cio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/#website\",\"url\":\"https:\/\/mostrafilmfestival.org\/xii\/\",\"name\":\"MOSTRA XII: Brazilian Film Festival\",\"description\":\"Brazilian Films with Social Conscience\",\"publisher\":{\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mostrafilmfestival.org\/xii\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/#organization\",\"name\":\"MOSTRA XII: Brazilian Film Festival\",\"url\":\"https:\/\/mostrafilmfestival.org\/xii\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/08\/Logo-Mostra-XII-Brazilian-Festival.png\",\"contentUrl\":\"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/08\/Logo-Mostra-XII-Brazilian-Festival.png\",\"width\":680,\"height\":312,\"caption\":\"MOSTRA XII: Brazilian Film Festival\"},\"image\":{\"@id\":\"https:\/\/mostrafilmfestival.org\/xii\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mostrafilmfestival\",\"https:\/\/x.com\/brazilianfilms\",\"https:\/\/www.instagram.com\/mostrafilmfestival\/\",\"https:\/\/www.linkedin.com\/company\/mostra-film-series\/\",\"https:\/\/www.youtube.com\/channel\/UCBcIXGvZdnH8yp7a2QapjEw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Lady From Est\u00e1cio - MOSTRA XII: Brazilian Film Festival","description":"Zulmira is an old mistress. One day she wakes up obsessed with the idea of dying. All she needs is a good coffin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/","og_locale":"en_US","og_type":"article","og_title":"The Lady From Est\u00e1cio - MOSTRA XII: Brazilian Film Festival","og_description":"Zulmira is an old mistress. One day she wakes up obsessed with the idea of dying. All she needs is a good coffin.","og_url":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/","og_site_name":"MOSTRA XII: Brazilian Film Festival","article_publisher":"https:\/\/www.facebook.com\/mostrafilmfestival","article_modified_time":"2021-10-18T22:21:56+00:00","og_image":[{"width":1000,"height":1469,"url":"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@brazilianfilms","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/","url":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/","name":"The Lady From Est\u00e1cio - MOSTRA XII: Brazilian Film Festival","isPartOf":{"@id":"https:\/\/mostrafilmfestival.org\/xii\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#primaryimage"},"image":{"@id":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#primaryimage"},"thumbnailUrl":"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg","datePublished":"2021-10-18T02:44:40+00:00","dateModified":"2021-10-18T22:21:56+00:00","description":"Zulmira is an old mistress. One day she wakes up obsessed with the idea of dying. All she needs is a good coffin.","breadcrumb":{"@id":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#primaryimage","url":"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg","contentUrl":"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/10\/adamadoestacio_cartaz_caixao_pt_peq.jpg","width":1000,"height":1469},{"@type":"BreadcrumbList","@id":"https:\/\/mostrafilmfestival.org\/xii\/films\/the-lady-from-estacio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mostrafilmfestival.org\/xii\/"},{"@type":"ListItem","position":2,"name":"The Lady From Est\u00e1cio"}]},{"@type":"WebSite","@id":"https:\/\/mostrafilmfestival.org\/xii\/#website","url":"https:\/\/mostrafilmfestival.org\/xii\/","name":"MOSTRA XII: Brazilian Film Festival","description":"Brazilian Films with Social Conscience","publisher":{"@id":"https:\/\/mostrafilmfestival.org\/xii\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mostrafilmfestival.org\/xii\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mostrafilmfestival.org\/xii\/#organization","name":"MOSTRA XII: Brazilian Film Festival","url":"https:\/\/mostrafilmfestival.org\/xii\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mostrafilmfestival.org\/xii\/#\/schema\/logo\/image\/","url":"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/08\/Logo-Mostra-XII-Brazilian-Festival.png","contentUrl":"https:\/\/mostrafilmfestival.org\/xii\/wp-content\/uploads\/2021\/08\/Logo-Mostra-XII-Brazilian-Festival.png","width":680,"height":312,"caption":"MOSTRA XII: Brazilian Film Festival"},"image":{"@id":"https:\/\/mostrafilmfestival.org\/xii\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mostrafilmfestival","https:\/\/x.com\/brazilianfilms","https:\/\/www.instagram.com\/mostrafilmfestival\/","https:\/\/www.linkedin.com\/company\/mostra-film-series\/","https:\/\/www.youtube.com\/channel\/UCBcIXGvZdnH8yp7a2QapjEw"]}]}},"_links":{"self":[{"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/portfolio\/1016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/comments?post=1016"}],"version-history":[{"count":3,"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/portfolio\/1016\/revisions"}],"predecessor-version":[{"id":1061,"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/portfolio\/1016\/revisions\/1061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/media\/1017"}],"wp:attachment":[{"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/media?parent=1016"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/tags?post=1016"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/mostrafilmfestival.org\/xii\/wp-json\/wp\/v2\/portfolio_entries?post=1016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}